{"id":214,"date":"2016-08-08T20:04:03","date_gmt":"2016-08-08T18:04:03","guid":{"rendered":"https:\/\/reisen.kriewel.de\/schweden2016\/?p=214"},"modified":"2016-08-08T21:30:17","modified_gmt":"2016-08-08T19:30:17","slug":"von-kalmar-weiter-nach-sueden","status":"publish","type":"post","link":"https:\/\/reisen.kriewel.de\/schweden2016\/2016\/08\/08\/von-kalmar-weiter-nach-sueden\/","title":{"rendered":"Von Kalmar weiter nach S\u00fcden&#8230;"},"content":{"rendered":"<p>Heute nahmen wir Abschied von Kalmar um wieder Richtung S\u00fcden zu fahren. Einen Zwischenstopp machten wir in Karlskrona. Dort unternahmen wir einen kleinen Stadtrundgang der uns zu einigen Sehensw\u00fcrdigkeiten wie den Geb\u00e4uden am &#8222;Stortorget&#8220; (Rathaus,  Dreifaltigkeitskirche), dem Admiralit\u00e4tsuhrenturm, der Admiralit\u00e4tskirche, der Statue des kleinen Nils Holgersson und Teilen des Hafens f\u00fchrte.<!--more--><br \/>\nAnschlie\u00dfend bummelten wir noch durch die Fu\u00dfg\u00e4ngerzone wo wir gut und (f\u00fcr schwedische Verh\u00e4ltnisse) g\u00fcnstig zu Mittag a\u00dfen. Dann fuhren wir weiter bis Karlshamn. Hier gab es, als ich Kind war, ein Eisschiff. Dort konnte man sein Softeis so oft in Streusel tunken (und die Auswahl war riesig) wie man wollte. Damals ein Erlebnis nah am Schlaraffenland. Ich musste unbedingt wissen ob es diesen Ort der Streuselgl\u00fcckseligkeit noch gab. Zum Gl\u00fcck konnte ich mich noch ungef\u00e4hr an die Lage erinnern. Leider war kein Schiff mehr da. Nur noch ein Kiosk. Hier hingen allerdings Bilder des Schiffes und wie sich herausgestellte wird es n\u00e4chstes Jahr wohl wieder ein Eisschiff geben. Ich werde wiederkommen. Das Eis mit Lakritzstreuseln war trotzdem sehr lecker. Nachdem wir Eis, Sonne und Hafenatmosph\u00e4re ausreichend genossen hatten, setzten wir unseren Weg fort. Heute \u00fcbernachten wir in Kristiansstadt um morgen die F\u00e4hre nach Bornholm zu nehmen.&nbsp;<\/p>\n<div id='gallery-1' class='gallery galleryid-214 gallery-columns-3 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/reisen.kriewel.de\/schweden2016\/files\/2016\/08\/IMG_1337.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/reisen.kriewel.de\/schweden2016\/files\/2016\/08\/IMG_1337-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/reisen.kriewel.de\/schweden2016\/files\/2016\/08\/IMG_1338.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/reisen.kriewel.de\/schweden2016\/files\/2016\/08\/IMG_1338-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/reisen.kriewel.de\/schweden2016\/files\/2016\/08\/IMG_1340.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/reisen.kriewel.de\/schweden2016\/files\/2016\/08\/IMG_1340-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/reisen.kriewel.de\/schweden2016\/files\/2016\/08\/IMG_1345.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/reisen.kriewel.de\/schweden2016\/files\/2016\/08\/IMG_1345-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/reisen.kriewel.de\/schweden2016\/files\/2016\/08\/IMG_1346.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/reisen.kriewel.de\/schweden2016\/files\/2016\/08\/IMG_1346-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/reisen.kriewel.de\/schweden2016\/files\/2016\/08\/IMG_1349.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/reisen.kriewel.de\/schweden2016\/files\/2016\/08\/IMG_1349-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/reisen.kriewel.de\/schweden2016\/files\/2016\/08\/IMG_1350.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/reisen.kriewel.de\/schweden2016\/files\/2016\/08\/IMG_1350-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/reisen.kriewel.de\/schweden2016\/files\/2016\/08\/IMG_1361.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/reisen.kriewel.de\/schweden2016\/files\/2016\/08\/IMG_1361-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/reisen.kriewel.de\/schweden2016\/files\/2016\/08\/IMG_1364.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/reisen.kriewel.de\/schweden2016\/files\/2016\/08\/IMG_1364-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/reisen.kriewel.de\/schweden2016\/files\/2016\/08\/IMG_1358.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/reisen.kriewel.de\/schweden2016\/files\/2016\/08\/IMG_1358-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/reisen.kriewel.de\/schweden2016\/files\/2016\/08\/IMG_1356.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/reisen.kriewel.de\/schweden2016\/files\/2016\/08\/IMG_1356-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/reisen.kriewel.de\/schweden2016\/files\/2016\/08\/IMG_1351.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/reisen.kriewel.de\/schweden2016\/files\/2016\/08\/IMG_1351-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p class=\"post-excerpt\">Heute nahmen wir Abschied von Kalmar um wieder Richtung S\u00fcden zu fahren. Einen Zwischenstopp machten wir in Karlskrona. Dort unternahmen&#8230;<\/p>\n","protected":false},"author":1,"featured_media":213,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-214","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/reisen.kriewel.de\/schweden2016\/wp-json\/wp\/v2\/posts\/214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reisen.kriewel.de\/schweden2016\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/reisen.kriewel.de\/schweden2016\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/reisen.kriewel.de\/schweden2016\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/reisen.kriewel.de\/schweden2016\/wp-json\/wp\/v2\/comments?post=214"}],"version-history":[{"count":9,"href":"https:\/\/reisen.kriewel.de\/schweden2016\/wp-json\/wp\/v2\/posts\/214\/revisions"}],"predecessor-version":[{"id":224,"href":"https:\/\/reisen.kriewel.de\/schweden2016\/wp-json\/wp\/v2\/posts\/214\/revisions\/224"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/reisen.kriewel.de\/schweden2016\/wp-json\/wp\/v2\/media\/213"}],"wp:attachment":[{"href":"https:\/\/reisen.kriewel.de\/schweden2016\/wp-json\/wp\/v2\/media?parent=214"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/reisen.kriewel.de\/schweden2016\/wp-json\/wp\/v2\/categories?post=214"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/reisen.kriewel.de\/schweden2016\/wp-json\/wp\/v2\/tags?post=214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}